{"id":9471,"date":"2022-12-12T14:30:02","date_gmt":"2022-12-12T19:30:02","guid":{"rendered":"https:\/\/www.culturaltraslahuella.com\/?p=9471"},"modified":"2023-04-15T12:02:42","modified_gmt":"2023-04-15T17:02:42","slug":"temblar-de-miedo","status":"publish","type":"post","link":"https:\/\/www.culturaltraslahuella.com\/en\/temblar-de-miedo\/","title":{"rendered":"Temblar de miedo"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"9471\" class=\"elementor elementor-9471\" data-elementor-settings=\"{&quot;page_masthead_image_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:900,&quot;sizes&quot;:[]},&quot;page_masthead_image_height_tablet&quot;:{&quot;unit&quot;:&quot;vh&quot;,&quot;size&quot;:70,&quot;sizes&quot;:[]},&quot;page_masthead_image_height_mobile&quot;:{&quot;unit&quot;:&quot;vh&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;page_masthead_background_position_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;page_masthead_background_position_x_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;page_masthead_background_position_x_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;page_masthead_background_position_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;page_masthead_background_position_y_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;page_masthead_background_position_y_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;rhye_hide_title_disabled&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7aa22bb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7aa22bb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e979bc8\" data-id=\"e979bc8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e363db8 elementor-widget elementor-widget-spacer\" data-id=\"e363db8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a54a1e2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a54a1e2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f14f7cb\" data-id=\"f14f7cb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-caa1507 elementor-widget elementor-widget-text-editor\" data-id=\"caa1507\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>&nbsp;<span style=\"color: #000000;\">\u00abEstoy flotando en un oc\u00e9ano de dolor. <\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\"><strong>&nbsp;No flotando \u2014sino nadando, mal\u2014 sin estilo.<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Pero no me hundo.\u00bb<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Susan Sontag<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>&nbsp;<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\"><i>Es un d\u00eda como cualquier otro, pero como casi todos los d\u00edas. Salgo a la calle, cierro la puerta, mis pulmones expulsan un aire que sale por mi boca, suspiro, mi cerebro tambi\u00e9n expulsa un pensamiento que se convierte en un deseo: \u201cque hoy no tenga tanto miedo\u201d. <\/i><br><\/span><\/p><p><span style=\"color: #000000;\">Camino por la acera, todo est\u00e1 bien porque no hay gente, no me cruzo con nadie, sigo caminando, de pronto escucho que alguien viene corriendo, mi coraz\u00f3n comienza a latir m\u00e1s r\u00e1pido, siento que se me va a salir del pecho, cada parte de mi cuerpo comienza a sudar, mis manos est\u00e1n totalmente mojadas y mis pensamientos totalmente nublados. La persona pasa por mi lado y me percato que est\u00e1 corriendo porque va a tomar un autob\u00fas. Miro mis manos y est\u00e1n temblando, estoy temblando de miedo.<\/span><\/p>\n<p><span style=\"color: #000000;\"><em><strong>\u00bfQu\u00e9 es el miedo?<\/strong> <\/em><\/span><\/p>\n<p><span style=\"color: #000000;\">Si me preguntaran \u00bfQu\u00e9 es el miedo? Esta ser\u00eda una peque\u00f1a descripci\u00f3n que lo definir\u00eda, pero la pregunta m\u00e1s importante ser\u00eda \u00bfPor qu\u00e9 tengo miedo? Mi nombre es Carolina, soy una de las muchas mujeres en el mundo que han sido v\u00edctimas de violencia basada en g\u00e9nero. En Colombia, seg\u00fan el Observatorio Nacional de Violencias de G\u00e9nero que pertenece al Ministerio de Salud y Protecci\u00f3n Social, al 8 de marzo del presente a\u00f1o se hab\u00edan reportado <strong>2144 <\/strong>casos de mujeres v\u00edctimas de violencia, esto quiere decir que en promedio 33 mujeres son maltratadas al d\u00eda, las cifras son alarmantes y m\u00e1s alarmantes los estragos que estos actos ocasionan en las v\u00edctimas.<\/span><\/p>\n<p><span style=\"color: #000000;\">Es precisamente de estos estragos, que muchas veces no son tratados adecuadamente por las entidades pertinentes, sobre lo que quiero escribir hoy. <\/span><\/p>\n<p><span style=\"color: #000000;\"><em><strong>Los sucesos<\/strong><\/em><\/span><\/p>\n<p><span style=\"color: #000000;\">Empezar\u00e9 contextualizando un poco mi estado de salud actual, hace varios meses tuve un accidente cerebrovascular (ACV) mi cerebro sufri\u00f3 un infarto que, en aspectos generales, es cuando se interrumpe o se reduce el suministro de sangre a una parte del cerebro, esto impide que el tejido cerebral reciba el ox\u00edgeno suficiente para que funcione con normalidad. Por su puesto que, un evento de esta magnitud deja secuelas, tanto fisiol\u00f3gicas como mentales y por esto se debe comenzar un proceso de rehabilitaci\u00f3n, en el cual me encuentro actualmente. Es en este proceso, es donde he reflexionado sobre la relaci\u00f3n del miedo, miedo que llevo sintiendo hace a\u00f1os a ra\u00edz de la violencia ejercida hacia m\u00ed, con este accidente cerebrovascular que he vivido.<\/span><\/p>\n<p><span style=\"color: #000000;\"><em><strong>Violencia y trauma<\/strong> <\/em><\/span><\/p>\n<p><span style=\"color: #000000;\">Hace aproximadamente 15 a\u00f1os, un sujeto me golpe\u00f3 en la calle, alguien totalmente desconocido para m\u00ed, nunca supe que pretend\u00eda y \u00bfpor qu\u00e9 lo hizo? creo que nunca lo voy a saber, este evento hizo que mi vida cambiara s\u00fabitamente, sin pedirlo. Desde ese momento el miedo ha estado presente cada d\u00eda en mi vida, nunca se ha ido y no s\u00e9 si alg\u00fan d\u00eda se ir\u00e1. Siento que todas las personas desconocidas a mi alrededor me quieren hacer da\u00f1o, miro a todos lados, a cada persona que se cruza por mi lado, estas sensaciones producen una especie de paranoia.&nbsp; Estos sentimientos tambi\u00e9n generan s\u00edntomas en mi cuerpo, como nerviosismo, aumento del ritmo card\u00edaco, sudoraci\u00f3n, respiraci\u00f3n acelerada, temblores y otros que se me escapan. Si analiz\u00e1ramos estos s\u00edntomas desde la psicolog\u00eda, presento un cuadro de ansiedad causado por de un evento traum\u00e1tico.&nbsp;<\/span><\/p>\n<p><span style=\"color: #000000;\">Un accidente cerebrovascular se presenta por varias causas, lo primero que los m\u00e9dicos deben analizar es cu\u00e1l fue la causa que lo provoc\u00f3, esto con el prop\u00f3sito de evitar que vuelva a ocurrir, ya que una vez sucede, la probabilidad de que se vuelva a presentar es alta. En mi caso, siguen estudiando esta causa, ya que desde la ciencia y medicamente hablando a\u00fan no hay un diagn\u00f3stico claro. Despu\u00e9s de varios meses de dolor f\u00edsico y espiritual, de incomprensi\u00f3n, de frustraci\u00f3n, de desolaci\u00f3n; pero de una ardua reflexi\u00f3n desde la experiencia, tanto corp\u00f3rea como cognitiva. Se ha formado una voz propia, donde puedo concluir que la causa est\u00e1 directamente relacionada con el miedo que he sentido por tantos a\u00f1os, y que siento a\u00fan. Imag\u00ednense ustedes, sentir esto que he descrito desde el principio, todos los d\u00edas. No hay que tener muchos conocimientos cient\u00edficos para saber o suponer, que un cuerpo en ese estado colapsar\u00e1 en alg\u00fan momento y el m\u00edo colaps\u00f3, se apag\u00f3.<\/span><\/p>\n<p><span style=\"color: #000000;\"><em><strong>Romper el silencio<\/strong> <\/em><\/span><\/p>\n<p><span style=\"color: #000000;\">Esta reflexi\u00f3n trascendi\u00f3 a la necesidad de romper el silencio, ahora esta es una voz que se alza, que grita con dolor: que las mujeres y todas las personas que hemos sido v\u00edctimas de violencia, en este caso f\u00edsica, no podemos quedarnos solo en una estad\u00edstica, necesitamos ayuda de nuestras familias, amigos y profesionales de las \u00e1reas id\u00f3neas para tratar este asunto, que paraliza nuestra vida. Necesitamos aprender a sobrellevar este dolor que, tal vez, nunca se ir\u00e1, pero que si no tratamos adecuadamente nos llevar\u00e1 a un hoyo negro del que no podremos salir nunca. A pesar que esta problem\u00e1tica cada vez es m\u00e1s visibilizada y abordada desde distintos \u00e1mbitos sociales, todav\u00eda falta mucho camino para salvaguardar las vidas de muchas y muchos humanos. Falta intervenci\u00f3n con respecto a los da\u00f1os colaterales que deja un evento tan traum\u00e1tico, falta accionar, difundir y expandir herramientas que nos ayuden a no quedarnos para siempre en la oscuridad en la que nos deja sumergidos la violencia.<\/span><\/p>\n<p><span style=\"color: #000000;\">Sinceramente y amorosamente, quiero extender mi voz de aliento y esperanza a todas y todos los que al leer esto se sientan identificados. Todos tenemos algo roto por dentro, la existencia en este mundo no es f\u00e1cil, existen distintas y varias razones, esta es la m\u00eda.&nbsp; Pero tambi\u00e9n he aprendido que, a veces si se nos muestran los distintos caminos que podemos tomar cuando nos sentimos perdidos y rotos, podr\u00edamos ahorrarnos un poco de dolor, de angustia y por qu\u00e9 no, podr\u00edamos dejar de temblar de miedo.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Un d\u00eda grit\u00e9 de miedo, hoy grito para que el miedo no nos mate la esperanza.<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>&nbsp;<\/strong><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7e71361 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7e71361\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-17c1072\" data-id=\"17c1072\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-94119a9 elementor-widget elementor-widget-text-editor\" data-id=\"94119a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<pre><span style=\"color: #000000;\">Autora : Carolina Tarazona<\/span><br \/><br \/><span style=\"color: #000000;\">Licenciada en Artes Visuales de la Universidad Pedag\u00f3gica Nacional, interesada en la investigaci\u00f3n de procesos de lectura y escritura, ha colaborado en la correcci\u00f3n de estilo del libro de cuentos infantiles: Re-cuerdos, escrito por Sergio Alejandro Rojas, tambi\u00e9n en proyectos de grado y otros escritos de car\u00e1cter acad\u00e9mico<\/span><\/pre>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Es un d\u00eda como cualquier otro, pero como casi todos los d\u00edas. Salgo a la calle, cierro la puerta, mis pulmones expulsan un aire que sale por mi boca, suspiro, mi cerebro tambi\u00e9n expulsa un pensamiento que se convierte en un deseo: \u201cque hoy no tenga tanto miedo\u201d&#8230;<\/p>","protected":false},"author":1,"featured_media":9472,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[65,149],"tags":[161,98,116,162,164],"class_list":["post-9471","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opinion","category-edicion-septiembre","tag-miedo","tag-salud","tag-sociedad","tag-temor","tag-trauma"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.culturaltraslahuella.com\/en\/wp-json\/wp\/v2\/posts\/9471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.culturaltraslahuella.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.culturaltraslahuella.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.culturaltraslahuella.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.culturaltraslahuella.com\/en\/wp-json\/wp\/v2\/comments?post=9471"}],"version-history":[{"count":0,"href":"https:\/\/www.culturaltraslahuella.com\/en\/wp-json\/wp\/v2\/posts\/9471\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.culturaltraslahuella.com\/en\/wp-json\/wp\/v2\/media\/9472"}],"wp:attachment":[{"href":"https:\/\/www.culturaltraslahuella.com\/en\/wp-json\/wp\/v2\/media?parent=9471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.culturaltraslahuella.com\/en\/wp-json\/wp\/v2\/categories?post=9471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.culturaltraslahuella.com\/en\/wp-json\/wp\/v2\/tags?post=9471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}